{"id":1372,"date":"2011-03-09T00:00:00","date_gmt":"2011-03-09T00:00:00","guid":{"rendered":"https:\/\/staging.project-asia.com\/index.php\/2011\/03\/09\/reisevortrag-in-nackenheim\/"},"modified":"2011-03-09T00:00:00","modified_gmt":"2011-03-09T00:00:00","slug":"reisevortrag-in-nackenheim","status":"publish","type":"post","link":"https:\/\/project-asia.com\/index.php\/2011\/03\/09\/reisevortrag-in-nackenheim\/","title":{"rendered":"Reisevortag in Nackenheim"},"content":{"rendered":"<hr size=\"2\" width=\"100%\" \/> <span style=\"font-size: 14px; font-weight: bold; text-align: left; line-height: 16px; padding-left: 0px; padding-top: 10px; font-family: Verdana,Arial,Helvetica,sans-serif; color: #ff6633\" class=\"contentheading\">Weltreise-Vortrag in Nackenheim!<\/span><i><span style=\"font-style: normal; font-weight: normal\" class=\"Apple-style-span\">&nbsp;<\/span><\/i> <\/p>\n<p> Am 5.11.2011 findet in Nackenheim, im Kettlersaal, Mainzer Strasse 7, unser erster &ouml;ffentlicher Weltreisevortrag statt!  <br \/> Es gibt nur 100 Karten &#8211; first come, first serve. <\/p>\n<p> Einlass um 18:30 Uhr. Start des Vortrags um 19:00 Uhr. Dauer ca. 110 Min.  <\/p>\n<p> Der Eintritt betr&auml;gt 5 Euro. Der Gewinn der Veranstaltung kommt einem guten Zweck zugute.<br \/> F&uuml;r weitere Spenden steht eine Kasse bereit oder kann &uuml;ber den Karten-Kauf abgewickelt werden (siehe unten). Auf Wunsch k&ouml;nnen hierzu anerkannte Spendenquittungen ausgestellt werden. <\/p>\n<p style=\"text-align: left; font-size: 10px\"> &nbsp; <img fetchpriority=\"high\" decoding=\"async\" class=\" alignleft size-full wp-image-1371\" src=\"https:\/\/project-asia.com\/wp-content\/uploads\/2011\/03\/flyer_vorderseite.jpg\" alt=\"Fyler-Vortrag\" style=\"margin: 5px; float: left\" title=\"Fyler-Vortrag\" height=\"299\" width=\"650\" srcset=\"https:\/\/project-asia.com\/wp-content\/uploads\/2011\/03\/flyer_vorderseite.jpg 650w, https:\/\/project-asia.com\/wp-content\/uploads\/2011\/03\/flyer_vorderseite-300x138.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Weltreise-Vortrag in Nackenheim!&nbsp; Am 5.11.2011 findet in Nackenheim, im Kettlersaal, Mainzer Strasse 7, unser erster &ouml;ffentlicher Weltreisevortrag statt! Es gibt nur 100 Karten &#8211; first come, first serve. Einlass um 18:30 Uhr. Start des Vortrags um 19:00 Uhr. Dauer ca. 110 Min. Der Eintritt betr&auml;gt 5 Euro. Der Gewinn der Veranstaltung kommt einem guten Zweck [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1371,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-berichte-a-news-berichte-a-news"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"_links":{"self":[{"href":"https:\/\/project-asia.com\/index.php\/wp-json\/wp\/v2\/posts\/1372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/project-asia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/project-asia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/project-asia.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/project-asia.com\/index.php\/wp-json\/wp\/v2\/comments?post=1372"}],"version-history":[{"count":0,"href":"https:\/\/project-asia.com\/index.php\/wp-json\/wp\/v2\/posts\/1372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/project-asia.com\/index.php\/wp-json\/wp\/v2\/media\/1371"}],"wp:attachment":[{"href":"https:\/\/project-asia.com\/index.php\/wp-json\/wp\/v2\/media?parent=1372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/project-asia.com\/index.php\/wp-json\/wp\/v2\/categories?post=1372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/project-asia.com\/index.php\/wp-json\/wp\/v2\/tags?post=1372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}